{"id":4273,"date":"2022-04-01T06:50:52","date_gmt":"2022-04-01T13:50:52","guid":{"rendered":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png"},"modified":"2022-04-01T06:50:52","modified_gmt":"2022-04-01T13:50:52","slug":"dee-p-2022-bronze-sponsors","status":"inherit","type":"attachment","link":"https:\/\/deepconnections.net\/jv_id\/how-you-can-help\/our-sponsors\/dee-p-2022-bronze-sponsors\/","title":{"rendered":"DEE-P 2022 Bronze Sponsors"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false},"class_list":["post-4273","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center<\/title>\n<meta name=\"description\" content=\"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png\" \/>\n<meta property=\"og:locale\" content=\"jv_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DEE-P 2022 Bronze Sponsors\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png\" \/>\n<meta property=\"og:site_name\" content=\"DEE-P Information Resource Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DEEPConnectionsEpilepsy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png\" \/>\n\t<meta property=\"og:image:width\" content=\"462\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DEE-P-2022-Bronze-Sponsors.png\",\"url\":\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DEE-P-2022-Bronze-Sponsors.png\",\"name\":\"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deepconnections.net\\\/#website\"},\"datePublished\":\"2022-04-01T13:50:52+00:00\",\"description\":\"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DEE-P-2022-Bronze-Sponsors.png#breadcrumb\"},\"inLanguage\":\"jv-ID\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DEE-P-2022-Bronze-Sponsors.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DEE-P-2022-Bronze-Sponsors.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/deepconnections.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How You Can Help\",\"item\":\"https:\\\/\\\/deepconnections.net\\\/how-you-can-help\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DEE-P Core Sponsors\",\"item\":\"https:\\\/\\\/deepconnections.net\\\/how-you-can-help\\\/our-sponsors\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"DEE-P 2022 Bronze Sponsors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deepconnections.net\\\/#website\",\"url\":\"https:\\\/\\\/deepconnections.net\\\/\",\"name\":\"DEE-P Connections\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/deepconnections.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deepconnections.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"jv-ID\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deepconnections.net\\\/#organization\",\"name\":\"DEE-P Connections Information & Resource Center\",\"url\":\"https:\\\/\\\/deepconnections.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"jv-ID\",\"@id\":\"https:\\\/\\\/deepconnections.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dee-p_logo.png\",\"contentUrl\":\"https:\\\/\\\/deepconnections.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dee-p_logo.png\",\"width\":362,\"height\":116,\"caption\":\"DEE-P Connections Information & Resource Center\"},\"image\":{\"@id\":\"https:\\\/\\\/deepconnections.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DEEPConnectionsEpilepsy\",\"https:\\\/\\\/www.instagram.com\\\/dee_pconnections\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center","description":"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png","og_locale":"jv_ID","og_type":"article","og_title":"DEE-P 2022 Bronze Sponsors","og_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png","og_site_name":"DEE-P Information Resource Center","article_publisher":"https:\/\/www.facebook.com\/DEEPConnectionsEpilepsy","og_image":[{"width":462,"height":464,"url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png","url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png","name":"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center","isPartOf":{"@id":"https:\/\/deepconnections.net\/#website"},"datePublished":"2022-04-01T13:50:52+00:00","description":"DEE-P 2022 Bronze Sponsors - DEE-P Information Resource Center","breadcrumb":{"@id":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png#breadcrumb"},"inLanguage":"jv-ID","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/deepconnections.net\/"},{"@type":"ListItem","position":2,"name":"How You Can Help","item":"https:\/\/deepconnections.net\/how-you-can-help\/"},{"@type":"ListItem","position":3,"name":"DEE-P Core Sponsors","item":"https:\/\/deepconnections.net\/how-you-can-help\/our-sponsors\/"},{"@type":"ListItem","position":4,"name":"DEE-P 2022 Bronze Sponsors"}]},{"@type":"WebSite","@id":"https:\/\/deepconnections.net\/#website","url":"https:\/\/deepconnections.net\/","name":"DEE-P Connections","description":"","publisher":{"@id":"https:\/\/deepconnections.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deepconnections.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"jv-ID"},{"@type":"Organization","@id":"https:\/\/deepconnections.net\/#organization","name":"DEE-P Connections Information & Resource Center","url":"https:\/\/deepconnections.net\/","logo":{"@type":"ImageObject","inLanguage":"jv-ID","@id":"https:\/\/deepconnections.net\/#\/schema\/logo\/image\/","url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2024\/09\/dee-p_logo.png","contentUrl":"https:\/\/deepconnections.net\/wp-content\/uploads\/2024\/09\/dee-p_logo.png","width":362,"height":116,"caption":"DEE-P Connections Information & Resource Center"},"image":{"@id":"https:\/\/deepconnections.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DEEPConnectionsEpilepsy","https:\/\/www.instagram.com\/dee_pconnections\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-300x300.png 300w, https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-100x100.png 100w, https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-150x150.png 150w, https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png 462w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":462,"height":464,"file":"2022\/04\/DEE-P-2022-Bronze-Sponsors.png","filesize":408322,"sizes":{"woocommerce_thumbnail":{"file":"DEE-P-2022-Bronze-Sponsors-300x300.png","width":300,"height":300,"filesize":175971,"uncropped":false,"mime_type":"image\/png","source_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-300x300.png"},"woocommerce_gallery_thumbnail":{"file":"DEE-P-2022-Bronze-Sponsors-100x100.png","width":100,"height":100,"filesize":22512,"mime_type":"image\/png","source_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-100x100.png"},"medium":{"file":"DEE-P-2022-Bronze-Sponsors-300x300.png","width":300,"height":300,"mime_type":"image\/png","source_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-300x300.png"},"thumbnail":{"file":"DEE-P-2022-Bronze-Sponsors-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors-150x150.png"},"full":{"file":"DEE-P-2022-Bronze-Sponsors.png","width":462,"height":464,"mime_type":"image\/png","source_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3341,"source_url":"https:\/\/deepconnections.net\/wp-content\/uploads\/2022\/04\/DEE-P-2022-Bronze-Sponsors.png","filename":"DEE-P-2022-Bronze-Sponsors.png","filesize":408322,"_links":{"self":[{"href":"https:\/\/deepconnections.net\/jv_id\/wp-json\/wp\/v2\/media\/4273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepconnections.net\/jv_id\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/deepconnections.net\/jv_id\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/deepconnections.net\/jv_id\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/deepconnections.net\/jv_id\/wp-json\/wp\/v2\/comments?post=4273"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":3341,"href":"https:\/\/deepconnections.net\/jv_id\/wp-json\/wp\/v2\/pages\/3341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}